{"id":5049,"date":"2016-07-18T10:18:32","date_gmt":"2016-07-18T08:18:32","guid":{"rendered":"http:\/\/www.refuerzo-forjados.com\/?p=5049"},"modified":"2018-04-04T17:20:10","modified_gmt":"2018-04-04T15:20:10","slug":"conector-certificado-para-forjados-de-madera-hormigon","status":"publish","type":"post","link":"https:\/\/tecnaria.com\/es\/conector-certificado-para-forjados-de-madera-hormigon\/","title":{"rendered":"Conector certificado para forjados de madera hormig\u00f3n"},"content":{"rendered":"<p>Para garantizar una realizaci\u00f3n y una consolidaci\u00f3n v\u00e1lidas de forjados de madera y hormig\u00f3n TECNARIA, la primera en Europa, ha sometido sus conectores BASE y MAXI a una minuciosa investigaci\u00f3n experimental seg\u00fan las normativas prescritas por el <strong>Euroc\u00f3digo 5<\/strong>.<br \/>\nLas caracter\u00edsticas de deformabilidad y resistencia del conector certificado fijado en la madera se han investigado de forma experimental en:<\/p>\n<ul>\n<li>CNR de Florencia &#8211; Instituto de Investigaci\u00f3n de la Madera: \u00abEvaluaci\u00f3n del comportamiento de conectores TECNARIA seg\u00fan la normativa Euroc\u00f3digo 5\u00bb.<\/li>\n<li>Laboratorio experimental para las pruebas sobre los materiales de construcci\u00f3n de la Facultad de Ingenier\u00eda del Instituto de Ciencia y T\u00e9cnica de la Construcci\u00f3n de la Universidad de Padua: \u00abEvaluaci\u00f3n del comportamiento de conectores TECNARIA seg\u00fan la normativa Euroc\u00f3digo 5\u00bb.<\/li>\n<li>Tecnaria ha conseguido la importante certificaci\u00f3n \u00ab<strong>AVIS TECHNIQUE<\/strong>\u00ab, aprobaci\u00f3n t\u00e9cnica para los conectores de tipo BASE y MAXI, para la realizaci\u00f3n y el refuerzo de forjados mixtos de madera y hormig\u00f3n. Por lo tanto, los productos Tecnaria y todo el m\u00e9todo de dise\u00f1o de forjados mixtos de madera y hormig\u00f3n han sido aprobados por la organizaci\u00f3n independiente francesa <strong>CSTB, Centre Scientifique et Technique du B\u00e2timent<\/strong>, miembro de EOTA, Organizaci\u00f3n Europea para las Aprobaciones T\u00e9cnicas. Descarga <a href=\"\/download\/legno\/download\/CT_L_CTL_CERTIFICAZIONE_AVIS_TECHNIQUE_EN.pdf\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a> el documento de certificaci\u00f3n (lengua inglesa).<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Para garantizar una realizaci\u00f3n y una consolidaci\u00f3n v\u00e1lidas de forjados de madera y hormig\u00f3n TECNARIA, la primera en Europa, ha sometido sus conectores BASE y MAXI a una minuciosa investigaci\u00f3n experimental seg\u00fan las normativas prescritas por el Euroc\u00f3digo 5. Las caracter\u00edsticas de deformabilidad y resistencia del conector certificado fijado en la madera se han investigado [&#8230;]\n","protected":false},"author":2,"featured_media":6085,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[253],"tags":[],"class_list":["post-5049","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rehabilitacion-de-forjados-de-madera"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conector certificado para forjados de madera hormig\u00f3n - Refuerzo forjados y conectores para madera, acero y hormig\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tecnaria.com\/es\/conector-certificado-para-forjados-de-madera-hormigon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conector certificado para forjados de madera hormig\u00f3n - Refuerzo forjados y conectores para madera, acero y hormig\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Para garantizar una realizaci\u00f3n y una consolidaci\u00f3n v\u00e1lidas de forjados de madera y hormig\u00f3n TECNARIA, la primera en Europa, ha sometido sus conectores BASE y MAXI a una minuciosa investigaci\u00f3n experimental seg\u00fan las normativas prescritas por el Euroc\u00f3digo 5. Las caracter\u00edsticas de deformabilidad y resistencia del conector certificado fijado en la madera se han investigado [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tecnaria.com\/es\/conector-certificado-para-forjados-de-madera-hormigon\/\" \/>\n<meta property=\"og:site_name\" content=\"Refuerzo forjados y conectores para madera, acero y hormig\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-18T08:18:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-04T15:20:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tecnaria.com\/wp-content\/uploads\/2015\/09\/avistec-e1455637022231.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Alberto Rosin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alberto Rosin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tecnaria.com\\\/es\\\/conector-certificado-para-forjados-de-madera-hormigon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecnaria.com\\\/es\\\/conector-certificado-para-forjados-de-madera-hormigon\\\/\"},\"author\":{\"name\":\"Alberto Rosin\",\"@id\":\"https:\\\/\\\/tecnaria.com\\\/#\\\/schema\\\/person\\\/a05dc69ec1405e951123d18726bcc2e4\"},\"headline\":\"Conector certificado para forjados de madera hormig\u00f3n\",\"datePublished\":\"2016-07-18T08:18:32+00:00\",\"dateModified\":\"2018-04-04T15:20:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tecnaria.com\\\/es\\\/conector-certificado-para-forjados-de-madera-hormigon\\\/\"},\"wordCount\":239,\"image\":{\"@id\":\"https:\\\/\\\/tecnaria.com\\\/es\\\/conector-certificado-para-forjados-de-madera-hormigon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tecnaria.com\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/avistec-e1455637022231.png\",\"articleSection\":[\"Rehabilitaci\u00f3n de Forjados de Madera\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tecnaria.com\\\/es\\\/conector-certificado-para-forjados-de-madera-hormigon\\\/\",\"url\":\"https:\\\/\\\/tecnaria.com\\\/es\\\/conector-certificado-para-forjados-de-madera-hormigon\\\/\",\"name\":\"Conector certificado para forjados de madera hormig\u00f3n - Refuerzo forjados y conectores para madera, acero y hormig\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecnaria.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tecnaria.com\\\/es\\\/conector-certificado-para-forjados-de-madera-hormigon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tecnaria.com\\\/es\\\/conector-certificado-para-forjados-de-madera-hormigon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tecnaria.com\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/avistec-e1455637022231.png\",\"datePublished\":\"2016-07-18T08:18:32+00:00\",\"dateModified\":\"2018-04-04T15:20:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/tecnaria.com\\\/#\\\/schema\\\/person\\\/a05dc69ec1405e951123d18726bcc2e4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tecnaria.com\\\/es\\\/conector-certificado-para-forjados-de-madera-hormigon\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tecnaria.com\\\/es\\\/conector-certificado-para-forjados-de-madera-hormigon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tecnaria.com\\\/es\\\/conector-certificado-para-forjados-de-madera-hormigon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tecnaria.com\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/avistec-e1455637022231.png\",\"contentUrl\":\"https:\\\/\\\/tecnaria.com\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/avistec-e1455637022231.png\",\"width\":400,\"height\":225},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tecnaria.com\\\/es\\\/conector-certificado-para-forjados-de-madera-hormigon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tecnaria.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conector certificado para forjados de madera hormig\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tecnaria.com\\\/#website\",\"url\":\"https:\\\/\\\/tecnaria.com\\\/\",\"name\":\"Refuerzo forjados y conectores para madera, acero y hormig\u00f3n\",\"description\":\"Rinforzo solai e connettori per acciaio, legno e calcestruzzo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tecnaria.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tecnaria.com\\\/#\\\/schema\\\/person\\\/a05dc69ec1405e951123d18726bcc2e4\",\"name\":\"Alberto Rosin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/40642ba39b2fe7297b4e52cbecacaf3901392a426fbd482477865ccb3ab3ff46?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/40642ba39b2fe7297b4e52cbecacaf3901392a426fbd482477865ccb3ab3ff46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/40642ba39b2fe7297b4e52cbecacaf3901392a426fbd482477865ccb3ab3ff46?s=96&d=mm&r=g\",\"caption\":\"Alberto Rosin\"},\"url\":\"https:\\\/\\\/tecnaria.com\\\/es\\\/author\\\/albros\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conector certificado para forjados de madera hormig\u00f3n - Refuerzo forjados y conectores para madera, acero y hormig\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tecnaria.com\/es\/conector-certificado-para-forjados-de-madera-hormigon\/","og_locale":"es_ES","og_type":"article","og_title":"Conector certificado para forjados de madera hormig\u00f3n - Refuerzo forjados y conectores para madera, acero y hormig\u00f3n","og_description":"Para garantizar una realizaci\u00f3n y una consolidaci\u00f3n v\u00e1lidas de forjados de madera y hormig\u00f3n TECNARIA, la primera en Europa, ha sometido sus conectores BASE y MAXI a una minuciosa investigaci\u00f3n experimental seg\u00fan las normativas prescritas por el Euroc\u00f3digo 5. Las caracter\u00edsticas de deformabilidad y resistencia del conector certificado fijado en la madera se han investigado [...]","og_url":"https:\/\/tecnaria.com\/es\/conector-certificado-para-forjados-de-madera-hormigon\/","og_site_name":"Refuerzo forjados y conectores para madera, acero y hormig\u00f3n","article_published_time":"2016-07-18T08:18:32+00:00","article_modified_time":"2018-04-04T15:20:10+00:00","og_image":[{"width":400,"height":225,"url":"https:\/\/tecnaria.com\/wp-content\/uploads\/2015\/09\/avistec-e1455637022231.png","type":"image\/png"}],"author":"Alberto Rosin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Alberto Rosin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tecnaria.com\/es\/conector-certificado-para-forjados-de-madera-hormigon\/#article","isPartOf":{"@id":"https:\/\/tecnaria.com\/es\/conector-certificado-para-forjados-de-madera-hormigon\/"},"author":{"name":"Alberto Rosin","@id":"https:\/\/tecnaria.com\/#\/schema\/person\/a05dc69ec1405e951123d18726bcc2e4"},"headline":"Conector certificado para forjados de madera hormig\u00f3n","datePublished":"2016-07-18T08:18:32+00:00","dateModified":"2018-04-04T15:20:10+00:00","mainEntityOfPage":{"@id":"https:\/\/tecnaria.com\/es\/conector-certificado-para-forjados-de-madera-hormigon\/"},"wordCount":239,"image":{"@id":"https:\/\/tecnaria.com\/es\/conector-certificado-para-forjados-de-madera-hormigon\/#primaryimage"},"thumbnailUrl":"https:\/\/tecnaria.com\/wp-content\/uploads\/2015\/09\/avistec-e1455637022231.png","articleSection":["Rehabilitaci\u00f3n de Forjados de Madera"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/tecnaria.com\/es\/conector-certificado-para-forjados-de-madera-hormigon\/","url":"https:\/\/tecnaria.com\/es\/conector-certificado-para-forjados-de-madera-hormigon\/","name":"Conector certificado para forjados de madera hormig\u00f3n - Refuerzo forjados y conectores para madera, acero y hormig\u00f3n","isPartOf":{"@id":"https:\/\/tecnaria.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tecnaria.com\/es\/conector-certificado-para-forjados-de-madera-hormigon\/#primaryimage"},"image":{"@id":"https:\/\/tecnaria.com\/es\/conector-certificado-para-forjados-de-madera-hormigon\/#primaryimage"},"thumbnailUrl":"https:\/\/tecnaria.com\/wp-content\/uploads\/2015\/09\/avistec-e1455637022231.png","datePublished":"2016-07-18T08:18:32+00:00","dateModified":"2018-04-04T15:20:10+00:00","author":{"@id":"https:\/\/tecnaria.com\/#\/schema\/person\/a05dc69ec1405e951123d18726bcc2e4"},"breadcrumb":{"@id":"https:\/\/tecnaria.com\/es\/conector-certificado-para-forjados-de-madera-hormigon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tecnaria.com\/es\/conector-certificado-para-forjados-de-madera-hormigon\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tecnaria.com\/es\/conector-certificado-para-forjados-de-madera-hormigon\/#primaryimage","url":"https:\/\/tecnaria.com\/wp-content\/uploads\/2015\/09\/avistec-e1455637022231.png","contentUrl":"https:\/\/tecnaria.com\/wp-content\/uploads\/2015\/09\/avistec-e1455637022231.png","width":400,"height":225},{"@type":"BreadcrumbList","@id":"https:\/\/tecnaria.com\/es\/conector-certificado-para-forjados-de-madera-hormigon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tecnaria.com\/es\/"},{"@type":"ListItem","position":2,"name":"Conector certificado para forjados de madera hormig\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/tecnaria.com\/#website","url":"https:\/\/tecnaria.com\/","name":"Refuerzo forjados y conectores para madera, acero y hormig\u00f3n","description":"Rinforzo solai e connettori per acciaio, legno e calcestruzzo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tecnaria.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/tecnaria.com\/#\/schema\/person\/a05dc69ec1405e951123d18726bcc2e4","name":"Alberto Rosin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/40642ba39b2fe7297b4e52cbecacaf3901392a426fbd482477865ccb3ab3ff46?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/40642ba39b2fe7297b4e52cbecacaf3901392a426fbd482477865ccb3ab3ff46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/40642ba39b2fe7297b4e52cbecacaf3901392a426fbd482477865ccb3ab3ff46?s=96&d=mm&r=g","caption":"Alberto Rosin"},"url":"https:\/\/tecnaria.com\/es\/author\/albros\/"}]}},"_links":{"self":[{"href":"https:\/\/tecnaria.com\/es\/wp-json\/wp\/v2\/posts\/5049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tecnaria.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tecnaria.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tecnaria.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tecnaria.com\/es\/wp-json\/wp\/v2\/comments?post=5049"}],"version-history":[{"count":5,"href":"https:\/\/tecnaria.com\/es\/wp-json\/wp\/v2\/posts\/5049\/revisions"}],"predecessor-version":[{"id":8812,"href":"https:\/\/tecnaria.com\/es\/wp-json\/wp\/v2\/posts\/5049\/revisions\/8812"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tecnaria.com\/es\/wp-json\/wp\/v2\/media\/6085"}],"wp:attachment":[{"href":"https:\/\/tecnaria.com\/es\/wp-json\/wp\/v2\/media?parent=5049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tecnaria.com\/es\/wp-json\/wp\/v2\/categories?post=5049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tecnaria.com\/es\/wp-json\/wp\/v2\/tags?post=5049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}